{"id":7804,"date":"2023-11-15T15:57:18","date_gmt":"2023-11-15T15:57:18","guid":{"rendered":"https:\/\/dev-e.kosmolat.eu\/product\/skropstu-tusa-podium-extreme\/"},"modified":"2024-01-09T18:43:39","modified_gmt":"2024-01-09T18:43:39","slug":"skropstu-tusa-podium-extreme","status":"publish","type":"product","link":"https:\/\/dev-e.kosmolat.eu\/lt\/produktas\/skropstu-tusa-podium-extreme\/","title":{"rendered":"BELOR DESIGN PODIUM EXTREME Blakstien\u0173 tu\u0161as, juodas, 11.7 g"},"content":{"rendered":"<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7806,"template":"","meta":[],"product_cat":[220],"product_tag":[],"class_list":["post-7804","product","type-product","status-publish","has-post-thumbnail","product_brand-belordizain","product_cat-tusai","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product\/7804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/media\/7806"}],"wp:attachment":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/media?parent=7804"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product_cat?post=7804"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product_tag?post=7804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}