{"id":7860,"date":"2023-11-15T15:58:53","date_gmt":"2023-11-15T15:58:53","guid":{"rendered":"https:\/\/dev-e.kosmolat.eu\/product\/suklis-sejai-4305\/"},"modified":"2024-01-09T19:00:40","modified_gmt":"2024-01-09T19:00:40","slug":"suklis-sejai-4305","status":"publish","type":"product","link":"https:\/\/dev-e.kosmolat.eu\/lt\/produktas\/suklis-sejai-4305\/","title":{"rendered":"DONEGAL Kosmetin\u0117s kempin\u0117l\u0117s, 4305"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp;<\/p>\n","protected":false},"featured_media":7986,"template":"","meta":[],"product_cat":[281],"product_tag":[],"class_list":["post-7860","product","type-product","status-publish","has-post-thumbnail","product_brand-donegal-sp-zo-o","product_cat-kempineles-ir-aplikatoriai","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product\/7860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/media\/7986"}],"wp:attachment":[{"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/media?parent=7860"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product_cat?post=7860"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lt\/wp-json\/wp\/v2\/product_tag?post=7860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}