{"id":17773,"date":"2023-11-22T15:19:29","date_gmt":"2023-11-22T15:19:29","guid":{"rendered":"https:\/\/dev-e.kosmolat.eu\/product\/skeres-kutikulai-neon-play\/"},"modified":"2024-01-10T01:01:41","modified_gmt":"2024-01-10T01:01:41","slug":"skeres-kutikulai-neon-play","status":"publish","type":"product","link":"https:\/\/dev-e.kosmolat.eu\/lv\/product\/skeres-kutikulai-neon-play\/","title":{"rendered":"\u0160\u0137\u0113res kutikulai &#8211; NEON-PLAY"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[712],"product_tag":[],"class_list":["post-17773","product","type-product","status-publish","product_brand-donegal-sp-zo-o","product_cat-davanu-komplekti-sievietem","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/dev-e.kosmolat.eu\/lv\/wp-json\/wp\/v2\/product\/17773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-e.kosmolat.eu\/lv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev-e.kosmolat.eu\/lv\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/dev-e.kosmolat.eu\/lv\/wp-json\/wp\/v2\/media?parent=17773"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lv\/wp-json\/wp\/v2\/product_cat?post=17773"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/lv\/wp-json\/wp\/v2\/product_tag?post=17773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}