{"id":21312,"date":"2023-11-22T17:27:41","date_gmt":"2023-11-22T17:27:41","guid":{"rendered":"https:\/\/dev-e.kosmolat.eu\/product\/testeris-33-tonis-lupu-spidums-pin-up-ultra-matt\/"},"modified":"2023-11-22T17:27:50","modified_gmt":"2023-11-22T17:27:50","slug":"testeris-33-tonis-lupu-spidums-pin-up-ultra-matt","status":"publish","type":"product","link":"https:\/\/dev-e.kosmolat.eu\/ru\/product\/testeris-33-tonis-lupu-spidums-pin-up-ultra-matt\/","title":{"rendered":"\u0422\u0435\u0441\u0442\u0435\u0440 \u0431\u043b\u0435\u0441\u043a\u0430 \u0434\u043b\u044f \u0433\u0443\u0431 PIN-UP ultra matt, 33 \u0442\u043e\u043d"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[964],"product_tag":[],"class_list":["post-21312","product","type-product","status-publish","product_cat-uncategorized-ru","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product\/21312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/media?parent=21312"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product_cat?post=21312"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product_tag?post=21312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}