{"id":21848,"date":"2023-11-22T17:55:31","date_gmt":"2023-11-22T17:55:31","guid":{"rendered":"https:\/\/dev-e.kosmolat.eu\/product\/testeris-tualetes-udens-sievietem-twee-coral-30-ml\/"},"modified":"2023-11-22T17:55:40","modified_gmt":"2023-11-22T17:55:40","slug":"testeris-tualetes-udens-sievietem-twee-coral-30-ml","status":"publish","type":"product","link":"https:\/\/dev-e.kosmolat.eu\/ru\/product\/testeris-tualetes-udens-sievietem-twee-coral-30-ml\/","title":{"rendered":"\u0422\u0435\u0441\u0442\u0435\u0440 \u0422\u0443\u0430\u043b\u0435\u0442\u043d\u0430\u044f  \u0432\u043e\u0434\u0430 \u0434\u043b\u044f \u0436\u0435\u043d\u0449\u0438\u043d \u00abTwee coral\u00bb (\u0422\u0432\u0438 \u043a\u043e\u0440\u0430\u043b) \/30\u043c\u043b"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[964],"product_tag":[],"class_list":["post-21848","product","type-product","status-publish","product_cat-uncategorized-ru","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product\/21848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/media?parent=21848"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product_cat?post=21848"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev-e.kosmolat.eu\/ru\/wp-json\/wp\/v2\/product_tag?post=21848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}